{"id":996,"count":131,"description":"","link":"https:\/\/almostalivelures.com\/wordpress\/product-category\/terminal-tackle\/","name":"Terminal Tackle","slug":"terminal-tackle","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/almostalivelures.com\/wordpress\/wp-json\/wp\/v2\/product_cat\/996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/almostalivelures.com\/wordpress\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/almostalivelures.com\/wordpress\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/almostalivelures.com\/wordpress\/wp-json\/wp\/v2\/product?product_cat=996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}